{"id":68,"count":5,"description":"","link":"https:\/\/thetravelfestival.com\/cheltenham\/travel-style\/nature-wildlife\/","name":"Nature &amp; Wildlife","slug":"nature-wildlife","taxonomy":"travel-style","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nature &amp; Wildlife Archives - Cheltenham Travel Festival<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thetravelfestival.com\/cheltenham\/travel-style\/nature-wildlife\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nature &amp; Wildlife Archives - Cheltenham Travel Festival\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thetravelfestival.com\/cheltenham\/travel-style\/nature-wildlife\/\" \/>\n<meta property=\"og:site_name\" content=\"Cheltenham Travel Festival\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/thetravelfestival.com\\\/cheltenham\\\/travel-style\\\/nature-wildlife\\\/\",\"url\":\"https:\\\/\\\/thetravelfestival.com\\\/cheltenham\\\/travel-style\\\/nature-wildlife\\\/\",\"name\":\"Nature &amp; Wildlife Archives - Cheltenham Travel Festival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thetravelfestival.com\\\/cheltenham\\\/#website\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thetravelfestival.com\\\/cheltenham\\\/#website\",\"url\":\"https:\\\/\\\/thetravelfestival.com\\\/cheltenham\\\/\",\"name\":\"Cheltenham Travel Festival\",\"description\":\"A festival bringing a world of travel experiences and expert advice\",\"publisher\":{\"@id\":\"https:\\\/\\\/thetravelfestival.com\\\/cheltenham\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thetravelfestival.com\\\/cheltenham\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thetravelfestival.com\\\/cheltenham\\\/#organization\",\"name\":\"Cheltenham Travel Festival\",\"url\":\"https:\\\/\\\/thetravelfestival.com\\\/cheltenham\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/thetravelfestival.com\\\/cheltenham\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thetravelfestival.com\\\/cheltenham\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/08\\\/CheltTravelFest_white_strip_logo.png\",\"contentUrl\":\"https:\\\/\\\/thetravelfestival.com\\\/cheltenham\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/08\\\/CheltTravelFest_white_strip_logo.png\",\"width\":4093,\"height\":530,\"caption\":\"Cheltenham Travel Festival\"},\"image\":{\"@id\":\"https:\\\/\\\/thetravelfestival.com\\\/cheltenham\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nature &amp; Wildlife Archives - Cheltenham Travel Festival","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thetravelfestival.com\/cheltenham\/travel-style\/nature-wildlife\/","og_locale":"en_GB","og_type":"article","og_title":"Nature &amp; Wildlife Archives - Cheltenham Travel Festival","og_url":"https:\/\/thetravelfestival.com\/cheltenham\/travel-style\/nature-wildlife\/","og_site_name":"Cheltenham Travel Festival","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/thetravelfestival.com\/cheltenham\/travel-style\/nature-wildlife\/","url":"https:\/\/thetravelfestival.com\/cheltenham\/travel-style\/nature-wildlife\/","name":"Nature &amp; Wildlife Archives - Cheltenham Travel Festival","isPartOf":{"@id":"https:\/\/thetravelfestival.com\/cheltenham\/#website"},"inLanguage":"en-GB"},{"@type":"WebSite","@id":"https:\/\/thetravelfestival.com\/cheltenham\/#website","url":"https:\/\/thetravelfestival.com\/cheltenham\/","name":"Cheltenham Travel Festival","description":"A festival bringing a world of travel experiences and expert advice","publisher":{"@id":"https:\/\/thetravelfestival.com\/cheltenham\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thetravelfestival.com\/cheltenham\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/thetravelfestival.com\/cheltenham\/#organization","name":"Cheltenham Travel Festival","url":"https:\/\/thetravelfestival.com\/cheltenham\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/thetravelfestival.com\/cheltenham\/#\/schema\/logo\/image\/","url":"https:\/\/thetravelfestival.com\/cheltenham\/wp-content\/uploads\/sites\/5\/2023\/08\/CheltTravelFest_white_strip_logo.png","contentUrl":"https:\/\/thetravelfestival.com\/cheltenham\/wp-content\/uploads\/sites\/5\/2023\/08\/CheltTravelFest_white_strip_logo.png","width":4093,"height":530,"caption":"Cheltenham Travel Festival"},"image":{"@id":"https:\/\/thetravelfestival.com\/cheltenham\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/thetravelfestival.com\/cheltenham\/wp-json\/wp\/v2\/travel-style\/68","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thetravelfestival.com\/cheltenham\/wp-json\/wp\/v2\/travel-style"}],"about":[{"href":"https:\/\/thetravelfestival.com\/cheltenham\/wp-json\/wp\/v2\/taxonomies\/travel-style"}],"wp:post_type":[{"href":"https:\/\/thetravelfestival.com\/cheltenham\/wp-json\/wp\/v2\/exhibitors?travel-style=68"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}